{"id":228,"date":"2021-02-19T10:36:00","date_gmt":"2021-02-19T13:36:00","guid":{"rendered":"http:\/\/pmra.com.br\/site\/?p=228"},"modified":"2021-12-08T10:37:59","modified_gmt":"2021-12-08T13:37:59","slug":"deliberacao-normativa-copam-no-240-2021","status":"publish","type":"post","link":"https:\/\/pmra.com.br\/site\/deliberacao-normativa-copam-no-240-2021\/","title":{"rendered":"DELIBERA\u00c7\u00c3O NORMATIVA COPAM N\u00ba 240\/2021"},"content":{"rendered":"\n<p>O Conselho Estadual de Pol\u00edtica\nAmbiental \u2013 COPAM publicou a&nbsp;Delibera\u00e7\u00e3o Normativa COPAM n\u00b0 240, de 29 de\nJaneiro de 2021, alterando a DN COPAM n\u00ba 217\/2017, que&nbsp;<em>&#8220;estabelece\ncrit\u00e9rios para classifica\u00e7\u00e3o, segundo o porte e potencial poluidor, bem como os\ncrit\u00e9rios locacionais a serem utilizados para defini\u00e7\u00e3o das modalidades de\nlicenciamento ambiental de empreendimentos e atividades utilizadores de\nrecursos ambientais no Estado de Minas Gerais&#8221;<\/em>,mormente\nno que tange aos seguintes pontos:&nbsp;<strong>(i)<\/strong>&nbsp;especificidades do\nLicenciamento Ambiental Simplificado por meio de Cadastro (LAS\/Cadastro);<strong>&nbsp;(ii)<\/strong>&nbsp;altera\u00e7\u00f5es\ndo gloss\u00e1rio de termos t\u00e9cnicos e ambientais e;&nbsp;<strong>(iii)<\/strong>&nbsp;altera\u00e7\u00f5es\nnos par\u00e2metros de algumas atividades licenci\u00e1veis.<\/p>\n\n\n\n<p>No que tange ao LAS\/Cadastro, houve\naltera\u00e7\u00e3o dos crit\u00e9rios de licenciamento das atividades de&nbsp;<em>&#8220;recapacita\u00e7\u00e3o\nou a repotencia\u00e7\u00e3o de Pequenas Centrais Hidrel\u00e9tricas \u2013 PCHs&#8221;&nbsp;<\/em>e&nbsp;<em>&#8220;Centrais\nGeradoras Hidrel\u00e9tricas \u2013 CGHs&#8221;.<\/em><\/p>\n\n\n\n<p>Dentre as atividades enquadradas nas\nclasses 1 ou 2 n\u00e3o pass\u00edveis de licenciamento ambiental na modalidade\nLAS\/Cadastro, foram inclu\u00eddas as atividades de&nbsp;<em>&#8220;Cremat\u00f3rio<\/em>&#8221;\ne&nbsp;<em>&#8220;Lavanderias industriais para tingimento e\/ou amaciamento e\/ou\noutros acabamentos qu\u00edmicos e\/ou lavagem a seco que utilizem solventes\norg\u00e2nicos&#8221;<\/em>.<\/p>\n\n\n\n<p>Houve, ainda, retifica\u00e7\u00e3o de algumas\nincoer\u00eancias textuais no gloss\u00e1rio constante do Anexo \u00danico da DN COPAM n\u00ba\n217\/2017, al\u00e9m de serem inclu\u00eddos novos termos t\u00e9cnicos e ambientais, a\nsaber:&nbsp;<\/p>\n\n\n\n<p><em>19-A. Lavanderias domiciliares \u2013\nsegmento que presta servi\u00e7os de lavagem dom\u00e9stica de pe\u00e7as do vestu\u00e1rio e\nartigos de cama, mesa e banho e\/ou objetos decorativos residenciais.<br>\n19-B. Lavanderias industriais \u2013 segmento especializado de lavanderia, integrado\nao processo produtivo da ind\u00fastria t\u00eaxtil e\/ou que atua como prestador de\nservi\u00e7o nas etapas de tingimento e\/ou amaciamento e\/ou outros acabamentos\nqu\u00edmicos e\/ou na lavagem a seco que utilize solventes org\u00e2nicos, exclu\u00eddas as\nlavanderias domiciliares e as lavanderias de uniformes, roupas de cama, mesa e\nbanho, al\u00e9m das lavanderias intraestabelecimentos de sa\u00fade e comerciais, como\nhotel, motel e restaurante.<br>\n(&#8230;)<br>\n41. Recapacita\u00e7\u00e3o \u2013 A interven\u00e7\u00e3o na CGH\/PCH em opera\u00e7\u00e3o ou paralisada, visando\nrestaurar a capacidade instalada declarada no processo de licenciamento\nambiental. (\u2026)<br>\n45-A. Reservat\u00f3rio \u2013 Massa de \u00e1gua, destinada ao armazenamento, \u00e0 regulariza\u00e7\u00e3o\nda vaz\u00e3o ou ao controle dos recursos h\u00eddricos. A partir da se\u00e7\u00e3o imediatamente\na montante de um barramento, \u00e9 todo volume dispon\u00edvel, cujas dimens\u00f5es s\u00e3o a\naltura atingida pela \u00e1gua e a \u00e1rea superficial abrangida (espelho d\u2019\u00e1gua). (\u2026)<br>\n63. Volume de dragagem \u2013 \u00c9 o volume total de material a ser dragado para\ndesassoreamento do corpo d\u2019\u00e1gua, devendo ser expresso em m\u00b3 (metro c\u00fabico).<\/em><\/p>\n\n\n\n<p>Al\u00e9m disso, foram feitas altera\u00e7\u00f5es\nrelevantes nos par\u00e2metros de algumas atividades licenci\u00e1veis, quais sejam:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>A-05-04-6 Pilha de rejeito\/est\u00e9ril de rochas\n     ornamentais e de revestimento, pegmatitos, gemas e minerais n\u00e3o met\u00e1licos;<\/li><li>B-09-05-9 Fabrica\u00e7\u00e3o de pe\u00e7as e acess\u00f3rios\n     para ve\u00edculos automotores e\/ou ferrovi\u00e1rios, exceto embarca\u00e7\u00f5es e\n     estruturas flutuantes;<\/li><li>C-09-03-2 Confec\u00e7\u00e3o de cal\u00e7ados de couro;<\/li><li>D-01-13-9 Formula\u00e7\u00e3o industrial de ra\u00e7\u00f5es\n     balanceadas e de alimentos preparados para animais, inclusive moagem de\n     gr\u00e3os, com finalidade comercial;<\/li><li>F-06-02-5 Lavanderias industriais para\n     tingimento e\/ou amaciamento e\/ou outros acabamentos qu\u00edmicos e\/ou lavagem\n     a seco que utilizem solventes org\u00e2nicos.<\/li><\/ul>\n\n\n\n<p>Vale destacar que as altera\u00e7\u00f5es\ntrazidas geram impactos diretos na classifica\u00e7\u00e3o e na modalidade de\nlicenciamento das atividades listadas.<br>\n<br>\nEm derradeiro, importante destacar que foi exclu\u00eddo o c\u00f3digo&nbsp;<em>\u201cF-01-01-5\nCentral de recebimento, armazenamento tempor\u00e1rio, triagem ou transbordo de\nsucata met\u00e1lica, papel, papel\u00e3o, pl\u00e1sticos ou vidro para reciclagem, n\u00e3o\ncontaminados com \u00f3leos, graxas, agrot\u00f3xicos ou produtos qu\u00edmicos\u201d<\/em>.<\/p>\n\n\n\n<p>A equipe do PMRA est\u00e1 \u00e0 disposi\u00e7\u00e3o\npara prestar quaisquer esclarecimentos adicionais sobre o assunto.<\/p>\n\n\n\n<p><br>\nTelefone: (31) 3290-4200<\/p>\n\n\n\n<p>E-mail: contato@pmra.com.br<\/p>\n\n\n\n<p>LinkedIn:\nhttps:\/\/www.linkedin.com\/company\/porto-miranda-rocha-&#038;-advogados\/\n\nInstagram: @pmradv Facebook: @pmra.adv\n\n\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Estadual de Pol\u00edtica Ambiental \u2013 COPAM publicou a&nbsp;Delibera\u00e7\u00e3o Normativa COPAM n\u00b0 240, de 29 de Janeiro de 2021, alterando a DN COPAM n\u00ba 217\/2017, que&nbsp;&#8220;estabelece crit\u00e9rios para classifica\u00e7\u00e3o, segundo o porte e potencial poluidor, bem como os crit\u00e9rios locacionais a serem utilizados para defini\u00e7\u00e3o das modalidades de licenciamento ambiental de empreendimentos e atividades&#8230;<\/p>\n","protected":false},"author":1,"featured_media":229,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/posts\/228"}],"collection":[{"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/comments?post=228"}],"version-history":[{"count":1,"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/posts\/228\/revisions"}],"predecessor-version":[{"id":230,"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/posts\/228\/revisions\/230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/media\/229"}],"wp:attachment":[{"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/media?parent=228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/categories?post=228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/tags?post=228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}