{"id":220,"date":"2021-04-08T10:29:00","date_gmt":"2021-04-08T13:29:00","guid":{"rendered":"http:\/\/pmra.com.br\/site\/?p=220"},"modified":"2021-12-08T10:31:34","modified_gmt":"2021-12-08T13:31:34","slug":"decreto-no-48-170-de-7-de-abril-de-2021","status":"publish","type":"post","link":"https:\/\/pmra.com.br\/site\/decreto-no-48-170-de-7-de-abril-de-2021\/","title":{"rendered":"DECRETO N\u00ba 48.170, DE 7 DE ABRIL DE 2021"},"content":{"rendered":"\n<p>Foi publicado no Di\u00e1rio Oficial de\nMinas Gerais, no dia 08.04.2021, o Decreto Estadual n\u00ba 48.170\/2021, que\nprorroga a suspens\u00e3o do curso do prazo processual de que trata o art. 1\u00ba do\nDecreto n\u00ba 48.155, de 19 de mar\u00e7o de 2021.<\/p>\n\n\n\n<p>Dessa forma, fica prorrogada, at\u00e9 18\nde abril de 2021, a suspens\u00e3o do curso do prazo processual&nbsp;relativo aos\nprocessos administrativos nos \u00f3rg\u00e3os e nas entidades do Poder Executivo.<\/p>\n\n\n\n<p>Vale destacar que o prazo processual\nque se iniciar ou se findar no per\u00edodo de suspens\u00e3o ficar\u00e1 prorrogado para o\nprimeiro dia \u00fatil seguinte ao t\u00e9rmino do per\u00edodo de suspens\u00e3o.<\/p>\n\n\n\n<p>A\nequipe do PMRA est\u00e1 \u00e0 disposi\u00e7\u00e3o para prestar quaisquer esclarecimentos\nadicionais sobre o assunto.<\/p>\n\n\n\n<p><br>\nTelefone: (31) 3290-4200<\/p>\n\n\n\n<p>E-mail: contato@pmra.com.br<\/p>\n\n\n\n<p>LinkedIn:\nhttps:\/\/www.linkedin.com\/company\/porto-miranda-rocha-&amp;-advogados\/<\/p>\n\n\n\n<p>Instagram:\n@pmradv<\/p>\n\n\n\n<p>Facebook:\n@pmra.adv<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foi publicado no Di\u00e1rio Oficial de Minas Gerais, no dia 08.04.2021, o Decreto Estadual n\u00ba 48.170\/2021, que prorroga a suspens\u00e3o do curso do prazo processual de que trata o art. 1\u00ba do Decreto n\u00ba 48.155, de 19 de mar\u00e7o de 2021. Dessa forma, fica prorrogada, at\u00e9 18 de abril de 2021, a suspens\u00e3o do curso&#8230;<\/p>\n","protected":false},"author":1,"featured_media":215,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/posts\/220"}],"collection":[{"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/comments?post=220"}],"version-history":[{"count":1,"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/posts\/220\/revisions"}],"predecessor-version":[{"id":221,"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/posts\/220\/revisions\/221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/media\/215"}],"wp:attachment":[{"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/media?parent=220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/categories?post=220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pmra.com.br\/site\/wp-json\/wp\/v2\/tags?post=220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}